{"id":6854,"date":"2022-08-17T09:04:52","date_gmt":"2022-08-17T07:04:52","guid":{"rendered":"https:\/\/www.koehlerpappen.de\/faq\/"},"modified":"2023-01-30T09:08:34","modified_gmt":"2023-01-30T08:08:34","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6854\" class=\"elementor elementor-6854 elementor-6678\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d0a14a elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"9d0a14a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-402b6bb elementor-invisible\" data-id=\"402b6bb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d072127 elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"d072127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.koehlerpappen.de\/fr\/accueil-koehlerpappen\/\">Page d'accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55c0297 elementor-widget elementor-widget-text-editor\" data-id=\"55c0297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>FAQ<\/h1>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d67319 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"9d67319\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_laptop&quot;:&quot;2&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-3 grid-col-tablet-2 grid-col-mobile-1 jet-listing-grid--2222 jet-equal-columns__wrapper\" data-queried-id=\"6854|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:2222,&quot;posts_num&quot;:50,&quot;columns&quot;:3,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;Aucune donn\\u00e9e n&#039;a \\u00e9t\\u00e9 trouv\\u00e9e&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;yes&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;empty_query&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:false,&quot;custom_query_id&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"posts\" data-listing-id=\"2222\" data-query-id=\"\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7259 jet-equal-columns\" data-post-id=\"7259\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Les produits K\u00f6hler sont-ils exempts de lignine et qu'est-ce que la lignine?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>La lignine est une substance de structure qui, outre la cellulose et d&rsquo;autres composants, est pr\u00e9sente dans le bois. Elle y provoque une rigidification suppl\u00e9mentaire des fibres. Dans le papier, c&rsquo;est un additif ind\u00e9sirable qui fait que le papier jaunit rapidement. Lors de l&rsquo;extraction de la cellulose, il est en grande partie s\u00e9par\u00e9 chimiquement de la cellulose.<\/p>\n<p>Notre carton est fabriqu\u00e9 \u00e0 100 % \u00e0 partir de la mati\u00e8re premi\u00e8re \u00ab\u00a0vieux papier m\u00e9lang\u00e9\u00a0\u00bb de cat\u00e9gorie 1.02. En raison de cette mati\u00e8re premi\u00e8re, nous ne pouvons pas donner de garantie sur les ingr\u00e9dients. Nous ne pouvons donc pas exclure la pr\u00e9sence d&rsquo;oligo-\u00e9l\u00e9ments de lignine dans notre carton.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7260 jet-equal-columns\" data-post-id=\"7260\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Du nonylph\u00e9nol et de l'\u00e9thoxylate de nonylph\u00e9nol dans les produits K\u00f6hler?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Le nonylph\u00e9nol est un pr\u00e9curseur des \u00e9thoxylates de nonylph\u00e9nol (NPE), le sous-groupe le plus important des \u00e9thoxylates d&rsquo;alkylph\u00e9nol (APE), qui sont surtout utilis\u00e9s comme substances actives de lavage (tensioactifs). Dans l&rsquo;environnement, les NPE se transforment \u00e0 nouveau en nonylph\u00e9nol toxique. Les APE peuvent \u00eatre pr\u00e9sents dans les pesticides, les produits de nettoyage et de d\u00e9sinfection ainsi que dans les emballages alimentaires, par exemple les films PVC. Ils sont \u00e9galement pr\u00e9sents dans les encres d&rsquo;imprimerie et les peintures murales ou les produits chimiques utilis\u00e9s pour l&rsquo;extraction du p\u00e9trole brut. Ils sont \u00e9galement utilis\u00e9s dans la fabrication de plastiques, de textiles, de cuir et de papier.<\/p>\n<p>Les nonylph\u00e9nols et les \u00e9thoxylates de nonylph\u00e9nol sont des substances qui peuvent \u00eatre utilis\u00e9es sp\u00e9cialement dans les adjuvants (produits de nettoyage).<\/p>\n<p>Nous vous confirmons par la pr\u00e9sente que ces deux substances ne sont pr\u00e9sentes dans aucun des adjuvants (produits de nettoyage) que nous utilisons pour la production. Nous pouvons donc exclure toute transmission de ces substances \u00e0 nos cartons.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7261 jet-equal-columns\" data-post-id=\"7261\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que sont les SPFO - sulfonates de perfluorooctane?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Les sulfonates de perfluorooctane (SPFO) ont \u00e9t\u00e9 utilis\u00e9s dans la fabrication de produits perfluor\u00e9s, utilis\u00e9s dans l&rsquo;industrie galvanique.<\/p>\n<p>L&rsquo;utilisation de notre mati\u00e8re premi\u00e8re, le vieux papier m\u00e9lang\u00e9 (1.02), ne nous permet pas d&rsquo;exclure la pr\u00e9sence de composants dans nos produits, mais ceux-ci sont normalement inf\u00e9rieurs \u00e0 la valeur limite en vigueur pour les produits, qui est de 0,1% (1000 ppm).<\/p>\n<p>Les agents de surface perfluor\u00e9s (PFT) utilis\u00e9s dans l&rsquo;industrie papeti\u00e8re pour repousser les graisses et mentionn\u00e9s dans la recommandation XXXVI ne contiennent pas non plus de SPFO dans l&rsquo;ordre de grandeur mentionn\u00e9 ci-dessus.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7262 jet-equal-columns\" data-post-id=\"7262\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu'est-ce que l'O-ph\u00e9nylph\u00e9nol?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>L&rsquo;O-ph\u00e9nylph\u00e9nol est express\u00e9ment autoris\u00e9 dans l&rsquo;industrie papeti\u00e8re au contact des aliments dans la recommandation XXXXVI (LMBG) Papiers, cartons et cartonnettes pour l&#8217;emballage alimentaire.<\/p>\n<p>Malgr\u00e9 cela, nous ne l&rsquo;utilisons pas dans notre production. N&rsquo;exclut toutefois pas que des traces d&rsquo;O-ph\u00e9nylph\u00e9nol soient pr\u00e9sentes dans nos produits dans la zone de la limite de d\u00e9tection analytique via la mati\u00e8re premi\u00e8re que nous utilisons, le vieux papier (1.02).<\/p>\n<p>Par ailleurs, nous tenons \u00e0 pr\u00e9ciser que l&rsquo;O-ph\u00e9nylph\u00e9nol est utilis\u00e9 comme conservateur autoris\u00e9 dans les oranges et les agrumes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7263 jet-equal-columns\" data-post-id=\"7263\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu'en est-il de l'utilisation des phtalates dans la fabrication du papier, du carton et des cartons?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Les phtalates sont utilis\u00e9s par exemple comme plastifiants pour les mati\u00e8res plastiques, mais ne sont pas utilis\u00e9s dans la fabrication du papier, du carton et du cartonnage. Des \u00e9tudes sur les aliments pour b\u00e9b\u00e9s ont r\u00e9v\u00e9l\u00e9 de tr\u00e8s faibles quantit\u00e9s de phtalates. Il s&rsquo;est av\u00e9r\u00e9 que ces substances ne proviennent pas de l&#8217;emballage. Elles sont plut\u00f4t dues \u00e0 leur pr\u00e9sence ubiquitaire, car des phtalates en quantit\u00e9s comparables ont \u00e9galement \u00e9t\u00e9 trouv\u00e9s dans d&rsquo;autres aliments et m\u00eame dans le lait maternel. [Source: C. B\u00f6hme: \u201eToxizit\u00e4t und Exposition einiger Bestandteile von Lebensmittelverpackungen\u201c, Bundesgesundhbl. 10\/97, pages 392-393]<\/p>\n<p>\u00c9tant donn\u00e9 que l&rsquo;on peut trouver des phtalates dans toutes les substances et tous les produits qui nous entourent, nous ne pouvons pas exclure que cette substance soit \u00e9galement pr\u00e9sente dans le carton que nous fabriquons.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7264 jet-equal-columns\" data-post-id=\"7264\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelle est la teneur en soufre de notre carton?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Le soufre \u00e9l\u00e9mentaire n&rsquo;est pas utilis\u00e9 dans la fabrication du carton. En revanche, les compos\u00e9s soufr\u00e9s inorganiques (par exemple l&rsquo;acide sulfurique, le sulfate d&rsquo;aluminium, le dithionite) et organiques (par exemple l&rsquo;acide formamidine-sulfinique) sont utilis\u00e9s pour ajuster le pH, pour encoller le carton ou pour blanchir les fibres de vieux papier. La majeure partie de ces compos\u00e9s soufr\u00e9s organiques et inorganiques se retrouve dans les eaux us\u00e9es d&rsquo;une usine de carton. Dans les stations d&rsquo;\u00e9puration des eaux us\u00e9es, les compos\u00e9s organiques soufr\u00e9s sont transform\u00e9s en sulfate stable.<\/p>\n<p>Les teneurs en compos\u00e9s soufr\u00e9s organiques et inorganiques dans le carton produit sont faibles. Ainsi, les teneurs en sulfate ne d\u00e9passent qu&rsquo;exceptionnellement 2 000 mg\/kg de carton. La teneur en soufre total, somme des compos\u00e9s organiques et inorganiques du soufre, un param\u00e8tre important lors de la combustion, est g\u00e9n\u00e9ralement inf\u00e9rieure \u00e0 1.000 mg S\/kg de carton. Elle est donc nettement inf\u00e9rieure \u00e0 la teneur en soufre total de la houille, du lignite ou du p\u00e9trole.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7265 jet-equal-columns\" data-post-id=\"7265\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Les produits K\u00f6hler sont-ils conformes \u00e0 la norme DIN EN 71, partie 3?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Nos cartons r\u00e9pondent aux exigences de la norme DIN EN 71, partie 3, en ce qui concerne les teneurs en antimoine, arsenic, baryum, plomb, cadmium, chrome, mercure et s\u00e9l\u00e9nium.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7266 jet-equal-columns\" data-post-id=\"7266\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Existe-t-il un certificat d'innocuit\u00e9 pour les cartons de K\u00f6hler?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Recommandation XXXVI \u00ab\u00a0Papiers, cartons et cartonnettes pour l&#8217;emballage alimentaire\u00a0\u00bb de l&rsquo;Office f\u00e9d\u00e9ral de la sant\u00e9 publique:<\/p>\n<p>Par la pr\u00e9sente, nous vous confirmons que notre carton est fabriqu\u00e9 selon les r\u00e8gles techniques g\u00e9n\u00e9ralement reconnues et qu&rsquo;il r\u00e9pond aux exigences de la loi allemande sur les denr\u00e9es alimentaires et les biens de consommation (LMBG) du 08.07.1993, r\u00e9vis\u00e9e le 09.09.1997, lorsqu&rsquo;il est utilis\u00e9 conform\u00e9ment \u00e0 sa destination, en contact avec des denr\u00e9es alimentaires s\u00e8ches et non grasses.<\/p>\n<p>Nous fabriquons notre carton conform\u00e9ment \u00e0 la recommandation XXXVI de l&rsquo;Institut f\u00e9d\u00e9ral allemand pour la protection sanitaire des consommateurs et la m\u00e9decine v\u00e9t\u00e9rinaire (BgVV &#8211; anciennement Office f\u00e9d\u00e9ral de la sant\u00e9 publique). Cette recommandation s&rsquo;intitule: \u00ab\u00a0Papiers, cartons et cartonnettes pour l&#8217;emballage alimentaire\u00a0\u00bb. Cela permet notamment de respecter les exigences des articles 30 et 31 de la LMBG (\u00ab\u00a0Interdictions pour la protection de la sant\u00e9\u00a0\u00bb et \u00ab\u00a0Transfert de substances aux denr\u00e9es alimentaires\u00a0\u00bb).<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7267 jet-equal-columns\" data-post-id=\"7267\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">K\u00f6hlerpappen GmbH est-elle certifi\u00e9e DIN EN ISO 9002?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Jusqu&rsquo;en septembre 2003, nous \u00e9tions certifi\u00e9s selon la norme DIN EN ISO 9002:1994. L&rsquo;audit de renouvellement n&rsquo;a pas \u00e9t\u00e9 effectu\u00e9 dans notre entreprise. Le traitement des clients ainsi que la fabrication s&rsquo;effectuent de mani\u00e8re analogue aux prescriptions des documents de certification initiaux.<\/p>\n<p>Une nouvelle certification selon la norme d\u00e9sormais en vigueur n&rsquo;est actuellement pas pr\u00e9vue.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7268 jet-equal-columns\" data-post-id=\"7268\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelles sont les caract\u00e9ristiques de temp\u00e9rature des produits K\u00f6hler?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Nos qualit\u00e9s K\u00d6HLERBOARD, K\u00d6HLERBOX et K\u00d6HLERPAC ont \u00e9t\u00e9 mesur\u00e9es au contact de la temp\u00e9rature dans notre laboratoire.<\/p>\n<p>Nous pouvons garantir que notre carton convient \u00e0 un contact direct avec les mat\u00e9riaux correspondants jusqu&rsquo;\u00e0 une temp\u00e9rature de 200 \u00b0C maximum.<\/p>\n<p>R\u00e9sultats obtenus:<\/p>\n<ul>\n<li>\u00e0 200 \u00b0C &#8211; pas de d\u00e9coloration constatable<\/li>\n<li>\u00e0 250 \u00b0C &#8211; l\u00e9g\u00e8re coloration brun\u00e2tre<\/li>\n<li>\u00e0 300 \u00b0C &#8211; forte coloration brun\u00e2tre<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7269 jet-equal-columns\" data-post-id=\"7269\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu'est-ce que la densit\u00e9 brute (poids sp\u00e9cifique)?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Au fil des ann\u00e9es, notre mati\u00e8re premi\u00e8re, le vieux papier m\u00e9lang\u00e9 (1.02), a subi des modifications n\u00e9gatives en termes de densit\u00e9 brute (poids sp\u00e9cifique) en raison des recyclages r\u00e9p\u00e9t\u00e9s. En adaptant la densit\u00e9 brute \u00e0 cette situation, le liss\u00e9 sera l\u00e9g\u00e8rement inf\u00e9rieur pour les versions liss\u00e9es.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7270 jet-equal-columns\" data-post-id=\"7270\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelle est la position de K\u00f6hlerpappen concernant le reach?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Pour la fabrication des cartons recycl\u00e9s et des cartons de bois que nous livrons, nous n&rsquo;utilisons aucune substance qui figure sur les listes SVHC du r\u00e8glement REACH.<\/p>\n<p>Si de telles substances \u00e9taient pr\u00e9sentes dans le papier recycl\u00e9 utilis\u00e9, il serait possible qu&rsquo;il en reste des traces dans le produit final, m\u00eame apr\u00e8s notre traitement des fibres.<\/p>\n<p>Mais celles-ci sont dans tous les cas nettement inf\u00e9rieures \u00e0 la limite mentionn\u00e9e dans le r\u00e8glement REACH, de sorte que nos produits sont ici aussi conformes \u00e0 REACH.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7271 jet-equal-columns\" data-post-id=\"7271\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Des huiles min\u00e9rales provenant de mat\u00e9riaux d'emballage dans les aliments?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>L&rsquo;industrie papeti\u00e8re europ\u00e9enne produit chaque ann\u00e9e environ 40 millions de tonnes de papier, de carton et de carton \u00e0 usage d&#8217;emballage, dont une grande partie est utilis\u00e9e pour emballer des denr\u00e9es alimentaires. Ils sont principalement fabriqu\u00e9s \u00e0 partir de fibres recycl\u00e9es. Les mati\u00e8res premi\u00e8res utilis\u00e9es sont des journaux, des magazines et des emballages usag\u00e9s en carton et en carton ondul\u00e9.<\/p>\n<p>La production s&rsquo;effectue selon les prescriptions l\u00e9gales en vigueur, qui sont adapt\u00e9es \u00e0 l&rsquo;\u00e9tat de la technique et aux connaissances scientifiques actuelles.<\/p>\n<p>Des \u00e9tudes r\u00e9centes ont r\u00e9v\u00e9l\u00e9 la pr\u00e9sence de traces d&rsquo;huiles provenant des encres d&rsquo;imprimerie utilis\u00e9es dans les journaux dans le papier, le carton et le carton recycl\u00e9, ainsi que dans les produits alimentaires qui y sont emball\u00e9s.<\/p>\n<p>Notre entreprise est en contact \u00e9troit avec les fabricants d&rsquo;encres d&rsquo;imprimerie, l&rsquo;industrie de l&rsquo;imprimerie, les \u00e9diteurs et l&rsquo;industrie de l&#8217;emballage par le biais de l&rsquo;association allemande des fabricants de papier (VDP) afin de r\u00e9soudre ce probl\u00e8me. Toutes les parties prenantes sont responsables de l&rsquo;innocuit\u00e9 des produits pour la sant\u00e9 et de la garantie d&rsquo;une \u00e9conomie durable du recyclage du papier, du carton et du carton.<\/p>\n<p>Actuellement, nous n&rsquo;avons pas connaissance d&rsquo;un risque concret pour les consommateurs.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7272 jet-equal-columns\" data-post-id=\"7272\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c0 quoi faut-il faire attention lors du stockage des produits de K\u00f6hler?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Les produits en papier sont en forte interaction avec l&rsquo;air ambiant.<\/p>\n<p>Cela est d\u00fb \u00e0 la propri\u00e9t\u00e9 hygroscopique des fibres de papier (naturelles), c&rsquo;est-\u00e0-dire \u00e0 leur capacit\u00e9 \u00e0 absorber l&rsquo;humidit\u00e9 ou \u00e0 la restituer \u00e0 un environnement plus sec.<\/p>\n<p>Ce n&rsquo;est que lorsqu&rsquo;il y a un \u00ab\u00a0\u00e9quilibre d&rsquo;humidit\u00e9\u00a0\u00bb entre l&rsquo;air et le papier ou le carton que la fibre se repose et cesse de \u00ab\u00a0travailler\u00a0\u00bb.<\/p>\n<p>Id\u00e9alement, les cartons devraient \u00eatre stock\u00e9s et trait\u00e9s dans les m\u00eames conditions climatiques standardis\u00e9es.<\/p>\n<p>Les temp\u00e9ratures dans les zones de stockage et de traitement devraient \u00eatre de 21\u00b0 Celsius et l&rsquo;humidit\u00e9 relative de 50 \u00e0 55 %.<\/p>\n<p>Lorsque le carton est transf\u00e9r\u00e9 d&rsquo;une zone de stockage froide \u00e0 une zone de traitement chauff\u00e9e, il faut laisser aux palettes suffisamment de temps pour se r\u00e9chauffer avant d&rsquo;enlever l&rsquo;enveloppe \u00e9tanche \u00e0 l&rsquo;humidit\u00e9 (film \u00e9tirable).<\/p>\n<p>Lorsque le carton froid est d\u00e9ball\u00e9 dans un environnement chaud et humide, l&rsquo;eau se condense sur les bords (bords coup\u00e9s) du carton, ce qui entra\u00eene une flexion des bords, des cartons ondul\u00e9s et une modification des dimensions (longueur, largeur, \u00e9paisseur).<\/p>\n<p>Il faut donc absolument laisser au carton environ 48 heures pour s&rsquo;acclimater.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7273 jet-equal-columns\" data-post-id=\"7273\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quelle est la valeur pH de nos produits et qu'est-ce que cela signifie?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Le pH indique la concentration d&rsquo;ions hydrog\u00e8ne dans une solution aqueuse. Les solutions dont le pH est inf\u00e9rieur \u00e0 7 ont une r\u00e9action acide. Les solutions dont le pH = 7 ont une r\u00e9action neutre. Celles dont le pH est sup\u00e9rieur \u00e0 7 ont une r\u00e9action alcaline. De nombreux processus vitaux se d\u00e9roulent dans certaines limites de pH.<\/p>\n<p>Le terme \u00ab\u00a0valeur pH\u00a0\u00bb s&rsquo;explique ainsi:<\/p>\n<p>Le petit \u00ab\u00a0p\u00a0\u00bb signifie \u00ab\u00a0potentia\u00a0\u00bb, le grand \u00ab\u00a0H\u00a0\u00bb est le symbole de l&rsquo;hydrog\u00e8ne. \u00ab\u00a0pH\u00a0\u00bb signifie donc \u00ab\u00a0potentia hydrogenii\u00a0\u00bb (en latin), ce qui revient \u00e0 dire \u00ab\u00a0puissance de la concentration en ions hydrog\u00e8ne\u00a0\u00bb.<\/p>\n<p>Les mesures en cours donnent une valeur neutre de nos produits d&rsquo;environ pH 7,0. En raison de l&rsquo;utilisation de notre mati\u00e8re premi\u00e8re, le vieux papier m\u00e9lang\u00e9 (1.02), nous ne pouvons malheureusement pas garantir la valeur indiqu\u00e9e. Des variations peuvent se produire en raison de la mati\u00e8re premi\u00e8re. Cela vaut pour tous les produits K\u00d6HLER fabriqu\u00e9s \u00e0 100 % \u00e0 partir de vieux papiers m\u00e9lang\u00e9s.<\/p>\n<p>Pour notre produit K\u00d6HLERlight 400, qui est fabriqu\u00e9 \u00e0 100 % \u00e0 partir de p\u00e2te de bois, les mesures en cours ont r\u00e9v\u00e9l\u00e9 une valeur neutre d&rsquo;environ pH 7,0. La plage de variation due \u00e0 l&rsquo;utilisation de la mati\u00e8re premi\u00e8re est tr\u00e8s faible, vous pouvez donc partir d&rsquo;une plage neutre.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-7274 jet-equal-columns\" data-post-id=\"7274\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"2222\" class=\"elementor elementor-2222\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc816 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0fd3170\" data-id=\"0fd3170\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d65f83 elementor-widget elementor-widget-accordion\" data-id=\"3d65f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6431\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6431\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">ausgeblendet<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6431\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6431\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6432\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6432\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu'est-ce que l'indice KAPPA et pour quels produits de charbonnage cet indice est-il important?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6432\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6432\"><p>Le nombre Kappa est une mesure de la duret\u00e9 relative, de l&rsquo;aptitude au blanchiment et du degr\u00e9 de d\u00e9sagr\u00e9gation des p\u00e2tes \u00e0 papier. Comme d&rsquo;autres m\u00e9thodes de d\u00e9termination du degr\u00e9 de d\u00e9composition, la d\u00e9termination de l&rsquo;indice kappa se base sur l&rsquo;oxydation des r\u00e9sidus de lignine. La consommation d&rsquo;agents oxydants (ici le permanganate de potassium) est une mesure de la teneur en lignine. L&rsquo;indice Kappa est donc une m\u00e9thode de d\u00e9termination de la p\u00e2te \u00e0 papier.<\/p>\n<p>\u00c9tant donn\u00e9 que l&rsquo;indice Kappa se r\u00e9f\u00e8re \u00e0 la consommation de mati\u00e8re premi\u00e8re cellulose et que notre consommation de mati\u00e8re premi\u00e8re pour les qualit\u00e9s K\u00d6HLERbox Special, K\u00d6HLERbox \u00ab\u00a0S\u00a0\u00bb Special et K\u00d6HLERbook Special (respectivement en r\u00e9f\u00e9rence \u00e0 la norme ISO 9706) repose sur des vieux papiers, nous devons exclure l&rsquo;indice Kappa comme mesure (<em><strong>voir nos fiches techniques<\/strong><\/em>).<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8861a76 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8861a76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88d0010 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"88d0010\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1c5745\" data-id=\"a1c5745\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da79a2 elementor-widget elementor-widget-heading\" data-id=\"9da79a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D'autres questions?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1172409 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1172409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prenez directement contact avec nous.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e20b0b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7e20b0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"mailto:info@koehlerboard.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">info@koehlerboard.com<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet D&rsquo;autres questions? Prenez directement contact avec nous. info@koehlerboard.com<\/p>\n","protected":false},"author":8,"featured_media":4694,"parent":6866,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6854","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<title>FAQ - K\u00f6hlerpappen GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ - K\u00f6hlerpappen GmbH\" \/>\n<meta property=\"og:description\" content=\"FAQ ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet D&rsquo;autres questions? Prenez directement contact avec nous. info@koehlerboard.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"K\u00f6hlerpappen GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T08:08:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/koehler-gebaeude-e1666596995564.png\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"589\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/\",\"url\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/\",\"name\":\"FAQ - K\u00f6hlerpappen GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.koehlerpappen.de\\\/wp-content\\\/uploads\\\/koehler-gebaeude-e1666596995564.png\",\"datePublished\":\"2022-08-17T07:04:52+00:00\",\"dateModified\":\"2023-01-30T08:08:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.koehlerpappen.de\\\/wp-content\\\/uploads\\\/koehler-gebaeude-e1666596995564.png\",\"contentUrl\":\"https:\\\/\\\/www.koehlerpappen.de\\\/wp-content\\\/uploads\\\/koehler-gebaeude-e1666596995564.png\",\"width\":607,\"height\":589},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/cartons\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page d'accueil\",\"item\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/accueil-koehlerpappen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartons\",\"item\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/pappen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/\",\"name\":\"K\u00f6hlerpappen GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#organization\",\"name\":\"K\u00f6hlerpappen GmbH\",\"url\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.koehlerpappen.de\\\/wp-content\\\/uploads\\\/logo_koehlerpappen.svg\",\"contentUrl\":\"https:\\\/\\\/www.koehlerpappen.de\\\/wp-content\\\/uploads\\\/logo_koehlerpappen.svg\",\"width\":134.22,\"height\":50.5,\"caption\":\"K\u00f6hlerpappen GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koehlerpappen.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"FAQ - K\u00f6hlerpappen GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/","og_locale":"fr_FR","og_type":"article","og_title":"FAQ - K\u00f6hlerpappen GmbH","og_description":"FAQ ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet ausgeblendet D&rsquo;autres questions? Prenez directement contact avec nous. info@koehlerboard.com","og_url":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/","og_site_name":"K\u00f6hlerpappen GmbH","article_modified_time":"2023-01-30T08:08:34+00:00","og_image":[{"width":607,"height":589,"url":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/koehler-gebaeude-e1666596995564.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/","url":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/","name":"FAQ - K\u00f6hlerpappen GmbH","isPartOf":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/#primaryimage"},"image":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/koehler-gebaeude-e1666596995564.png","datePublished":"2022-08-17T07:04:52+00:00","dateModified":"2023-01-30T08:08:34+00:00","breadcrumb":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/#primaryimage","url":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/koehler-gebaeude-e1666596995564.png","contentUrl":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/koehler-gebaeude-e1666596995564.png","width":607,"height":589},{"@type":"BreadcrumbList","@id":"https:\/\/www.koehlerpappen.de\/fr\/cartons\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page d'accueil","item":"https:\/\/www.koehlerpappen.de\/fr\/accueil-koehlerpappen\/"},{"@type":"ListItem","position":2,"name":"Cartons","item":"https:\/\/www.koehlerpappen.de\/fr\/pappen\/"},{"@type":"ListItem","position":3,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/www.koehlerpappen.de\/fr\/#website","url":"https:\/\/www.koehlerpappen.de\/fr\/","name":"K\u00f6hlerpappen GmbH","description":"","publisher":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.koehlerpappen.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.koehlerpappen.de\/fr\/#organization","name":"K\u00f6hlerpappen GmbH","url":"https:\/\/www.koehlerpappen.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.koehlerpappen.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/logo_koehlerpappen.svg","contentUrl":"https:\/\/www.koehlerpappen.de\/wp-content\/uploads\/logo_koehlerpappen.svg","width":134.22,"height":50.5,"caption":"K\u00f6hlerpappen GmbH"},"image":{"@id":"https:\/\/www.koehlerpappen.de\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/pages\/6854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/comments?post=6854"}],"version-history":[{"count":3,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/pages\/6854\/revisions"}],"predecessor-version":[{"id":6902,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/pages\/6854\/revisions\/6902"}],"up":[{"embeddable":true,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/pages\/6866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/media\/4694"}],"wp:attachment":[{"href":"https:\/\/www.koehlerpappen.de\/fr\/wp-json\/wp\/v2\/media?parent=6854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}